{"id":1049,"date":"2022-12-17T07:16:06","date_gmt":"2022-12-17T06:16:06","guid":{"rendered":"https:\/\/axtra.wealcoder.com\/?page_id=1049"},"modified":"2023-09-30T15:35:48","modified_gmt":"2023-09-30T13:35:48","slug":"nase-sluzby","status":"publish","type":"page","link":"https:\/\/keytoart.cz\/index.php\/nase-sluzby\/","title":{"rendered":"Na\u0161e slu\u017eby"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1049\" class=\"elementor elementor-1049\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cdab66 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3cdab66\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d5b7b16\" data-id=\"d5b7b16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8484311 elementor-widget elementor-widget-axtra_digital_solution\" data-id=\"8484311\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"axtra_digital_solution.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n        \n    <!-- Hero area start -->\n    <section class=\"solution__area\">\n    \t<div class=\"container hero-line\"><\/div>\n        <div class=\"solution__wrapper\">\n                        <div class=\"solution__left\">\n                                <div class=\"solution__img-1\">\n                \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/woman-holding-glass.png\" alt=\"Solution Image\">\n                <\/div>\n                                                <div class=\"solution__img-2\">\n                \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/people-wine-party.png\" alt=\"Solution Image\">\n                <\/div>\n                            <\/div>\n        \t            \n\t\t\t            <div class=\"solution__mid\">\n                <h1 class=\"solution__title animation__char_come\">Co um\u00edme?<\/h1>                <p>Zorganizujeme pro v\u00e1s \u0161irokou \u0161k\u00e1lu event\u016f - firemn\u00ed akce, spole\u010densk\u00e9 akce, kongresy, ve\u010d\u00edrky, teambuilding. Dejte n\u00e1m svoji vizi a v\u0161e ostatn\u00ed nechte na n\u00e1s!<\/p>            <\/div>\n        \t            \n                        <div class=\"solution__right\">\n                <div class=\"solution__img-3\">\n                \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/conference.png\" alt=\"Solution Image\">\n                <\/div>\n            <\/div>\n                    <\/div>\n    \t\n                <div class=\"container pb-130\">\n            <div class=\"row\">\n                <div class=\"col-xxl-12\">\n                    <div class=\"solution__btm\">\n                        <ul>\n                                                        <li>Spolehlivost <\/li>\n                                                        <li>Kreativita <\/li>\n                                                        <li>Zku\u0161enosti<\/li>\n                                                    <\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n                \n    \t        <div class=\"solution__shape\">\n            <img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/themes\/axtra\/assets\/images\/icon\/1.png\" alt=\"Shape Image\" class=\"shape-1\">\n            <img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/themes\/axtra\/assets\/images\/\/icon\/2.png\" alt=\"Shape Image\" class=\"shape-2\">\n            <img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/themes\/axtra\/assets\/images\/\/icon\/3.png\" alt=\"Shape Image\" class=\"shape-3\">\n            <img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/themes\/axtra\/assets\/images\/\/icon\/4.png\" alt=\"Shape Image\" class=\"shape-4\">\n            <img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/themes\/axtra\/assets\/images\/\/icon\/5.png\" alt=\"Shape Image\" class=\"shape-5\">\n        <\/div>\n            <\/section>\n    <!-- Hero area end -->\n              \n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6551a2c elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6551a2c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d9d64b\" data-id=\"0d9d64b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c16baf elementor-widget elementor-widget-axtra_our_services\" data-id=\"6c16baf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"axtra_our_services.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n        \n    <!-- Service area start -->\n    <section class=\"service__area pt-110 pb-150\">\n        <div class=\"container\">\n                        <div class=\"row\">\n                <div class=\"col-xxl-4 col-xl-4 col-lg-4 col-md-4\">\n                    <div class=\"sec-title-wrapper wrap\">\n                        <h2 class=\"sec-sub-title title-anim\">Eventy<\/h2>                        <h3 class=\"sec-title title-anim\">Realizujeme va\u0161e ud\u00e1losti<\/h3>                    <\/div>\n                <\/div>\n                \n\t\t\t\t                            <\/div>\n        \t            \n            <div class=\"service__list-wrapper\">\n                <div class=\"row\">\n                    <div class=\"col-xxl-4 col-xl-4 col-lg-0 col-md-0\">\n                        <div class=\"service__img-wrapper\">\n                                                        <img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/pexels-sebastian-ervi-1763075.jpg\" alt=\"Service Image\" class=\"service__img img-1 active\">\n                            \n                            <span class=\"shape-box-1 current\"><\/span>\n                                                        <img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/jakob-dalbjorn-cuKJre3nyYc-unsplash.jpg\" alt=\"Service Image\" class=\"service__img img-2 \">\n                            \n                            <span class=\"shape-box-2 \"><\/span>\n                                                        <img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/pexels-luis-quintero-2833037.jpg\" alt=\"Service Image\" class=\"service__img img-3 \">\n                            \n                            <span class=\"shape-box-3 \"><\/span>\n                                                        <img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/stephen-arnold-xSTQzSLJA4c-unsplash.jpg\" alt=\"Service Image\" class=\"service__img img-4 \">\n                            \n                            <span class=\"shape-box-4 \"><\/span>\n                                                        <img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/hannah-busing-Zyx1bK9mqmA-unsplash.jpg\" alt=\"Service Image\" class=\"service__img img-5 \">\n                            \n                            <span class=\"shape-box-5 \"><\/span>\n                                                    <\/div>\n                    <\/div>\n                    \n                    <div class=\"col-xxl-8 col-xl-8 col-lg-12 col-md-12\">\n                        <div class=\"service__list\">\n                        \t                            <a href=\"https:\/\/keytoart.cz\/index.php\/service\/spolecenske-akce\/\" target=\"_blank\">\n                                <div class=\"service__item animation_home1_service\" data-service=\"1\">\n                                \t<div class=\"service__number\"><span>01<\/span><\/div>\n                                    <div class=\"service__title-wrapper\">\n                                        <h4 class=\"service__title\">Spole\u010densk\u00e9 akce<\/h4>\n                                    <\/div>\n                                    <div class=\"service__text\">\n                                        <p>Spole\u010densk\u00e9 akce Na\u0161e spole\u010dnost se specializuje na po\u0159\u00e1d\u00e1n\u00ed spole\u010densk\u00fdch akc\u00ed, kter\u00e9 p\u0159ekonaj\u00ed va\u0161e o\u010dek\u00e1v\u00e1n\u00ed a stanou se nezapomenuteln\u00fdm z\u00e1\u017eitkem pro ...<\/p>\n                                    <\/div>\n                                    <div class=\"service__link\">\n                                    \t<p><i class=\"fa-solid fa-arrow-right\"><\/i><\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        \t                            <a href=\"https:\/\/keytoart.cz\/index.php\/service\/firemni-akce\/\" target=\"_blank\">\n                                <div class=\"service__item animation_home1_service\" data-service=\"2\">\n                                \t<div class=\"service__number\"><span>02<\/span><\/div>\n                                    <div class=\"service__title-wrapper\">\n                                        <h4 class=\"service__title\">Firemn\u00ed akce<\/h4>\n                                    <\/div>\n                                    <div class=\"service__text\">\n                                        <p>Firemn\u00ed akce Po\u0159\u00e1d\u00e1n\u00ed a organizace firemn\u00edch akc\u00ed \u2013 ano, jsme to my, co v\u00e1m pom\u016f\u017eeme vytrhnout trn z paty. P\u0159em\u00fd\u0161l\u00edme ...<\/p>\n                                    <\/div>\n                                    <div class=\"service__link\">\n                                    \t<p><i class=\"fa-solid fa-arrow-right\"><\/i><\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        \t                            <a href=\"https:\/\/keytoart.cz\/index.php\/service\/kongresy\/\" target=\"_blank\">\n                                <div class=\"service__item animation_home1_service\" data-service=\"3\">\n                                \t<div class=\"service__number\"><span>03<\/span><\/div>\n                                    <div class=\"service__title-wrapper\">\n                                        <h4 class=\"service__title\">Kongresy<\/h4>\n                                    <\/div>\n                                    <div class=\"service__text\">\n                                        <p>Kongresy Najdeme vhodn\u00e9 prostory, kter\u00e9 citliv\u011b dopln\u00edme zaj\u00edmav\u00fdm programem, aktivitami, kter\u00e9 V\u00e1m pomohou odreagovat se od celodenn\u00ed n\u00e1ro\u010dnosti kongres\u016f a ...<\/p>\n                                    <\/div>\n                                    <div class=\"service__link\">\n                                    \t<p><i class=\"fa-solid fa-arrow-right\"><\/i><\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        \t                            <a href=\"https:\/\/keytoart.cz\/index.php\/service\/incentivni-programy\/\" target=\"_blank\">\n                                <div class=\"service__item animation_home1_service\" data-service=\"4\">\n                                \t<div class=\"service__number\"><span>04<\/span><\/div>\n                                    <div class=\"service__title-wrapper\">\n                                        <h4 class=\"service__title\">Incentivn\u00ed programy<\/h4>\n                                    <\/div>\n                                    <div class=\"service__text\">\n                                        <p>Incentivn\u00ed programy Kdykoliv a kdekoliv nejen v \u010cesk\u00e9 republice, ale i v zahrani\u010d\u00ed pro V\u00e1s a Va\u0161e klienty, partnery p\u0159iprav\u00edme ...<\/p>\n                                    <\/div>\n                                    <div class=\"service__link\">\n                                    \t<p><i class=\"fa-solid fa-arrow-right\"><\/i><\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        \t                            <a href=\"https:\/\/keytoart.cz\/index.php\/service\/teambuilding\/\" target=\"_blank\">\n                                <div class=\"service__item animation_home1_service\" data-service=\"5\">\n                                \t<div class=\"service__number\"><span>05<\/span><\/div>\n                                    <div class=\"service__title-wrapper\">\n                                        <h4 class=\"service__title\">Teambuilding<\/h4>\n                                    <\/div>\n                                    <div class=\"service__text\">\n                                        <p>Teambuilding Teambuildingov\u00e9 programy \u2013 nebudeme v\u00e1m zbyte\u010dn\u011b popisovat, co je to teambuilding. V\u017edy\u0165 to stejn\u011b v\u0161ichni zn\u00e1te. Kdysi se tomu ...<\/p>\n                                    <\/div>\n                                    <div class=\"service__link\">\n                                    \t<p><i class=\"fa-solid fa-arrow-right\"><\/i><\/p>\n                                    <\/div>\n                                <\/div>\n                            <\/a>\n                        \t                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n    <!-- Service area end -->\n    \n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-124eb20 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"124eb20\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-adbd62d\" data-id=\"adbd62d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a186903 elementor-widget elementor-widget-axtra_our_client\" data-id=\"a186903\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"axtra_our_client.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n    \n\t\n\t    \n    <!-- Brand area start -->\n    <section class=\"brand__area\">\n        <div class=\"container line pt-140 pb-110 no-p\">\n        \t<span class=\"line-3\"><\/span>            <div class=\"row\">\n                <div class=\"col-xxl-12\">\n                    <h2 class=\"brand__title-3 title-anim\">Poznejte n\u011bkter\u00e9 z na\u0161ich klient\u016f... <\/h2>                    <div class=\"brand__list brand-gap\">\n                    \t                        <div class=\"brand__item-2 fade_bottom\">\n                        \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/db-shenker.jpg\" alt=\"Brand Logo\">\n                        <\/div>\n                    \t                        <div class=\"brand__item-2 fade_bottom\">\n                        \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/continental.jpg\" alt=\"Brand Logo\">\n                        <\/div>\n                    \t                        <div class=\"brand__item-2 fade_bottom\">\n                        \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/globus.jpg\" alt=\"Brand Logo\">\n                        <\/div>\n                    \t                        <div class=\"brand__item-2 fade_bottom\">\n                        \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/antolin.jpg\" alt=\"Brand Logo\">\n                        <\/div>\n                    \t                        <div class=\"brand__item-2 fade_bottom\">\n                        \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/forvia.jpg\" alt=\"Brand Logo\">\n                        <\/div>\n                    \t                        <div class=\"brand__item-2 fade_bottom\">\n                        \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/09\/foxconn.jpg\" alt=\"Brand Logo\">\n                        <\/div>\n                    \t                        <div class=\"brand__item-2 fade_bottom\">\n                        \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/skoda.jpg\" alt=\"Brand Logo\">\n                        <\/div>\n                    \t                        <div class=\"brand__item-2 fade_bottom\">\n                        \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/auffer-design.jpg\" alt=\"Brand Logo\">\n                        <\/div>\n                    \t                        <div class=\"brand__item-2 fade_bottom\">\n                        \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/bombardier.jpg\" alt=\"Brand Logo\">\n                        <\/div>\n                    \t                        <div class=\"brand__item-2 fade_bottom\">\n                        \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/aeg.jpg\" alt=\"Brand Logo\">\n                        <\/div>\n                    \t                        <div class=\"brand__item-2 fade_bottom\">\n                        \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/johnson-controls.jpg\" alt=\"Brand Logo\">\n                        <\/div>\n                    \t                        <div class=\"brand__item-2 fade_bottom\">\n                        \t<img decoding=\"async\" src=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/megatech.jpg\" alt=\"Brand Logo\">\n                        <\/div>\n                    \t \n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n    <!-- Brand area end -->\n\t\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-558d8d6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"558d8d6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-508d008\" data-id=\"508d008\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9446066 elementor-widget elementor-widget-axtra_call_to_action\" data-id=\"9446066\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"axtra_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\n        \n    <!-- CTA area start -->\n    <section class=\"cta__area\">\n        <div class=\"container line  pb-110\">\n        \t<div class=\"line-3\"><\/div>\n            <div class=\"row\">\n                <div class=\"col-xxl-12\">\n                    <div class=\"cta__content\">\n                        <p class=\"cta__sub-title\">kontaktujte n\u00e1s<\/p>                        <h2 class=\"cta__title title-anim\">Poj\u010fme se pobavit o va\u0161em eventu!<\/h2>                                                <div id=\"btn_wrapper\">\n                            <a href=\"https:\/\/keytoart.cz\/index.php\/kontakt\/\" target=\"_blank\" rel=\"nofollow\" class=\"wc-btn-primary btn-hover btn-item\"><span><\/span>kontaktujte n\u00e1s <i class=\"fa-solid fa-arrow-right\"><\/i><\/a>\n                        <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n    <!-- CTA area end -->\n    \n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Co um\u00edme? Zorganizujeme pro v\u00e1s \u0161irokou \u0161k\u00e1lu event\u016f &#8211; firemn\u00ed akce, spole\u010densk\u00e9 akce, kongresy, ve\u010d\u00edrky, teambuilding. Dejte n\u00e1m svoji vizi a v\u0161e ostatn\u00ed nechte na n\u00e1s! Spolehlivost Kreativita Zku\u0161enosti Eventy Realizujeme va\u0161e ud\u00e1losti 01 Spole\u010densk\u00e9 akce Spole\u010densk\u00e9 akce Na\u0161e spole\u010dnost se specializuje na po\u0159\u00e1d\u00e1n\u00ed spole\u010densk\u00fdch akc\u00ed, kter\u00e9 p\u0159ekonaj\u00ed va\u0161e o\u010dek\u00e1v\u00e1n\u00ed a stanou se nezapomenuteln\u00fdm z\u00e1\u017eitkem [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"tpl-default-elementor.php","meta":{"footnotes":""},"class_list":["post-1049","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Na\u0161e slu\u017eby - Key To Art Agency<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/keytoart.cz\/index.php\/nase-sluzby\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Na\u0161e slu\u017eby - Key To Art Agency\" \/>\n<meta property=\"og:description\" content=\"Co um\u00edme? Zorganizujeme pro v\u00e1s \u0161irokou \u0161k\u00e1lu event\u016f &#8211; firemn\u00ed akce, spole\u010densk\u00e9 akce, kongresy, ve\u010d\u00edrky, teambuilding. Dejte n\u00e1m svoji vizi a v\u0161e ostatn\u00ed nechte na n\u00e1s! Spolehlivost Kreativita Zku\u0161enosti Eventy Realizujeme va\u0161e ud\u00e1losti 01 Spole\u010densk\u00e9 akce Spole\u010densk\u00e9 akce Na\u0161e spole\u010dnost se specializuje na po\u0159\u00e1d\u00e1n\u00ed spole\u010densk\u00fdch akc\u00ed, kter\u00e9 p\u0159ekonaj\u00ed va\u0161e o\u010dek\u00e1v\u00e1n\u00ed a stanou se nezapomenuteln\u00fdm z\u00e1\u017eitkem [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/keytoart.cz\/index.php\/nase-sluzby\/\" \/>\n<meta property=\"og:site_name\" content=\"Key To Art Agency\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-30T13:35:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/woman-holding-glass.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Odhadovan\u00e1 doba \u010dten\u00ed\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/keytoart.cz\\\/index.php\\\/nase-sluzby\\\/\",\"url\":\"https:\\\/\\\/keytoart.cz\\\/index.php\\\/nase-sluzby\\\/\",\"name\":\"Na\u0161e slu\u017eby - Key To Art Agency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/keytoart.cz\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/keytoart.cz\\\/index.php\\\/nase-sluzby\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/keytoart.cz\\\/index.php\\\/nase-sluzby\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/keytoart.cz\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/woman-holding-glass.png\",\"datePublished\":\"2022-12-17T06:16:06+00:00\",\"dateModified\":\"2023-09-30T13:35:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/keytoart.cz\\\/index.php\\\/nase-sluzby\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/keytoart.cz\\\/index.php\\\/nase-sluzby\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/keytoart.cz\\\/index.php\\\/nase-sluzby\\\/#primaryimage\",\"url\":\"https:\\\/\\\/keytoart.cz\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/woman-holding-glass.png\",\"contentUrl\":\"https:\\\/\\\/keytoart.cz\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/woman-holding-glass.png\",\"width\":435,\"height\":472},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/keytoart.cz\\\/index.php\\\/nase-sluzby\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/keytoart.cz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Na\u0161e slu\u017eby\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/keytoart.cz\\\/#website\",\"url\":\"https:\\\/\\\/keytoart.cz\\\/\",\"name\":\"Key To Art Agency\",\"description\":\"Eventov\u00e1 agentura, kter\u00e1 po\u0159\u00e1d\u00e1 \u0161irokou \u0161k\u00e1lu event\u016f jak pro firmy tak i soukrom\u00e9 osoby. Po\u0159\u00e1d\u00e1me spole\u010densk\u00e9 akce, firemn\u00ed akce, teambuildingy, incentivn\u00ed programy, kongresy, konference a mnohem v\u00edce!\",\"publisher\":{\"@id\":\"https:\\\/\\\/keytoart.cz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/keytoart.cz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/keytoart.cz\\\/#organization\",\"name\":\"Key To Art Agency\",\"url\":\"https:\\\/\\\/keytoart.cz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/keytoart.cz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/keytoart.cz\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-logo-no_shadow.png\",\"contentUrl\":\"https:\\\/\\\/keytoart.cz\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cropped-logo-no_shadow.png\",\"width\":250,\"height\":250,\"caption\":\"Key To Art Agency\"},\"image\":{\"@id\":\"https:\\\/\\\/keytoart.cz\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Na\u0161e slu\u017eby - Key To Art Agency","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/keytoart.cz\/index.php\/nase-sluzby\/","og_locale":"cs_CZ","og_type":"article","og_title":"Na\u0161e slu\u017eby - Key To Art Agency","og_description":"Co um\u00edme? Zorganizujeme pro v\u00e1s \u0161irokou \u0161k\u00e1lu event\u016f &#8211; firemn\u00ed akce, spole\u010densk\u00e9 akce, kongresy, ve\u010d\u00edrky, teambuilding. Dejte n\u00e1m svoji vizi a v\u0161e ostatn\u00ed nechte na n\u00e1s! Spolehlivost Kreativita Zku\u0161enosti Eventy Realizujeme va\u0161e ud\u00e1losti 01 Spole\u010densk\u00e9 akce Spole\u010densk\u00e9 akce Na\u0161e spole\u010dnost se specializuje na po\u0159\u00e1d\u00e1n\u00ed spole\u010densk\u00fdch akc\u00ed, kter\u00e9 p\u0159ekonaj\u00ed va\u0161e o\u010dek\u00e1v\u00e1n\u00ed a stanou se nezapomenuteln\u00fdm z\u00e1\u017eitkem [&hellip;]","og_url":"https:\/\/keytoart.cz\/index.php\/nase-sluzby\/","og_site_name":"Key To Art Agency","article_modified_time":"2023-09-30T13:35:48+00:00","og_image":[{"url":"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/woman-holding-glass.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Odhadovan\u00e1 doba \u010dten\u00ed":"8 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/keytoart.cz\/index.php\/nase-sluzby\/","url":"https:\/\/keytoart.cz\/index.php\/nase-sluzby\/","name":"Na\u0161e slu\u017eby - Key To Art Agency","isPartOf":{"@id":"https:\/\/keytoart.cz\/#website"},"primaryImageOfPage":{"@id":"https:\/\/keytoart.cz\/index.php\/nase-sluzby\/#primaryimage"},"image":{"@id":"https:\/\/keytoart.cz\/index.php\/nase-sluzby\/#primaryimage"},"thumbnailUrl":"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/woman-holding-glass.png","datePublished":"2022-12-17T06:16:06+00:00","dateModified":"2023-09-30T13:35:48+00:00","breadcrumb":{"@id":"https:\/\/keytoart.cz\/index.php\/nase-sluzby\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/keytoart.cz\/index.php\/nase-sluzby\/"]}]},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/keytoart.cz\/index.php\/nase-sluzby\/#primaryimage","url":"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/woman-holding-glass.png","contentUrl":"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/woman-holding-glass.png","width":435,"height":472},{"@type":"BreadcrumbList","@id":"https:\/\/keytoart.cz\/index.php\/nase-sluzby\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/keytoart.cz\/"},{"@type":"ListItem","position":2,"name":"Na\u0161e slu\u017eby"}]},{"@type":"WebSite","@id":"https:\/\/keytoart.cz\/#website","url":"https:\/\/keytoart.cz\/","name":"Key To Art Agency","description":"Eventov\u00e1 agentura, kter\u00e1 po\u0159\u00e1d\u00e1 \u0161irokou \u0161k\u00e1lu event\u016f jak pro firmy tak i soukrom\u00e9 osoby. Po\u0159\u00e1d\u00e1me spole\u010densk\u00e9 akce, firemn\u00ed akce, teambuildingy, incentivn\u00ed programy, kongresy, konference a mnohem v\u00edce!","publisher":{"@id":"https:\/\/keytoart.cz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/keytoart.cz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/keytoart.cz\/#organization","name":"Key To Art Agency","url":"https:\/\/keytoart.cz\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/keytoart.cz\/#\/schema\/logo\/image\/","url":"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/cropped-logo-no_shadow.png","contentUrl":"https:\/\/keytoart.cz\/wp-content\/uploads\/2023\/04\/cropped-logo-no_shadow.png","width":250,"height":250,"caption":"Key To Art Agency"},"image":{"@id":"https:\/\/keytoart.cz\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/keytoart.cz\/index.php\/wp-json\/wp\/v2\/pages\/1049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keytoart.cz\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/keytoart.cz\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/keytoart.cz\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/keytoart.cz\/index.php\/wp-json\/wp\/v2\/comments?post=1049"}],"version-history":[{"count":34,"href":"https:\/\/keytoart.cz\/index.php\/wp-json\/wp\/v2\/pages\/1049\/revisions"}],"predecessor-version":[{"id":3811,"href":"https:\/\/keytoart.cz\/index.php\/wp-json\/wp\/v2\/pages\/1049\/revisions\/3811"}],"wp:attachment":[{"href":"https:\/\/keytoart.cz\/index.php\/wp-json\/wp\/v2\/media?parent=1049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}